{"id":80,"count":4,"description":"","link":"http:\/\/bauer-garten.de\/referenzen\/category\/projektort-evtl-inihrernaehenachplz\/14167-zehlendorf\/","name":"14167-Zehlendorf","slug":"14167-zehlendorf","taxonomy":"category","parent":33,"meta":[],"_links":{"self":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories\/80"}],"collection":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories\/33"}],"wp:post_type":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/posts?categories=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}