{"id":19,"count":47,"description":"","link":"http:\/\/bauer-garten.de\/referenzen\/category\/art-der-arbeiten\/hausgarten\/","name":"Hausgarten","slug":"hausgarten","taxonomy":"category","parent":4,"meta":[],"_links":{"self":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories\/19"}],"collection":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories\/4"}],"wp:post_type":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/posts?categories=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}