{"id":140,"count":1,"description":"","link":"http:\/\/bauer-garten.de\/referenzen\/category\/projektort-evtl-inihrernaehenachplz\/14478-potsdam\/","name":"14478-Potsdam","slug":"14478-potsdam","taxonomy":"category","parent":33,"meta":[],"_links":{"self":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories\/140"}],"collection":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/categories\/33"}],"wp:post_type":[{"href":"http:\/\/bauer-garten.de\/referenzen\/wp-json\/wp\/v2\/posts?categories=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}